{"id":22901,"date":"2023-07-24T16:55:45","date_gmt":"2023-07-24T15:55:45","guid":{"rendered":"https:\/\/www.ordineavvocatipescara.it\/?p=22901"},"modified":"2023-07-24T16:55:45","modified_gmt":"2023-07-24T15:55:45","slug":"informativa-106-23-iscrizione-elenco-179-ter-trasmissione-accordo-negoziazione-assistita-in-materia-di-famiglia","status":"publish","type":"post","link":"https:\/\/www.ordineavvocatipescara.it\/index.php\/2023\/07\/24\/informativa-106-23-iscrizione-elenco-179-ter-trasmissione-accordo-negoziazione-assistita-in-materia-di-famiglia\/","title":{"rendered":"Informativa 106\/23 (ISCRIZIONE ELENCO 179 TER &#8211; TRASMISSIONE ACCORDO NEGOZIAZIONE ASSISTITA IN MATERIA DI FAMIGLIA)"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong><span style=\"color: #000080;\">Lettera informativa n. 106\/23 del 24.07.2023<\/span><\/strong><\/p>\n<p><span style=\"color: #000080;\">\u00a0<\/span><\/p>\n<p><span style=\"color: #000080;\">\u00a0<\/span><strong><span style=\"color: #ff0000;\">\u00a0<\/span><\/strong><\/p>\n<p><strong><span style=\"color: #000080;\"><span style=\"color: #ff0000;\">1.TRIBUNALE PESCARA \u2013 ISCRIZIONE \u00a0ELENCO 179 TER<\/span> <\/span><\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000080;\">Si trasmettono il verbale della riunione 18.07.2023 del Comitato costituito ai sensi dell\u2019art. 179 ter secondo comma ed il successivo provvedimento 19.07.23 del Presidente del Tribunale di Pescara con allegata modulistica, recanti disposizioni sulle <strong><span style=\"color: #333399;\">modalit\u00e0 di presentazione delle domande<\/span><\/strong> <span style=\"color: #333399;\">di inserimento<\/span> nell\u2019elenco dei professionisti che provvedono alle operazioni di vendita ex <a href=\"https:\/\/www.ordineavvocatipescara.it\/wp-content\/uploads\/2023\/07\/testo-ART-179-TER-novellato.pdf\">art. 179 ter disp. att. cpc<\/a> (<em>come modificato dall\u2019 art. 4, co. 11, lett. e) D.Lgs. 10.10.2022 n. 149<\/em>). <a href=\"https:\/\/www.ordineavvocatipescara.it\/wp-content\/uploads\/2023\/07\/modalita-presentazione-domande.pdf\">CLICCA QUI<\/a><br \/>\n<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000080;\">Si segnala, in particolare, che:<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000080;\">&#8211; con riferimento al requisito di cui al co. 5, lett. a) dell\u2019art. 179 ter, il Comitato ha precisato che, <strong><span style=\"color: #333399;\">per incarico<em> \u201c<\/em>svolto nel quinquennio precedente<em>\u201d, <\/em>deve intendersi<\/span><\/strong><em> \u201cun incarico pendente nel quinquennio antecedente alla data di presentazione della domanda, sebbene conferito in data precedente, e durante il quale sia stato depositato al fascicolo telematico almeno un avviso di vendita; da considerarsi equipollente a tale attivit\u00e0 \u00e8 quella effettuata in seno alle divisioni endoesecutive\u201d;<\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000080;\">&#8211; la <strong><span style=\"color: #333399;\">DOMANDA<\/span><\/strong>, firmata digitalmente, con marca da bollo da \u20ac 16 da apporre e \u201cannullare\u201d da parte del richiedente, va presentata <strong><span style=\"color: #333399;\">esclusivamente a mezzo PEC all\u2019indirizzo del Tribunale<\/span><\/strong>: prot.tribunale.pescara@giustiziacert.it, a partire dal 24 luglio 2023 ed <strong><span style=\"color: #333399;\">entro il 16 ottobre 2023<\/span><\/strong>.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000080;\">ALLEGATO: <em><a href=\"https:\/\/www.ordineavvocatipescara.it\/wp-content\/uploads\/2023\/07\/Modulo_di_domanda_di_iscrizione_all_elenco_ex_art_179ter_disp_att_cpc.docx\">Modulo_di_domanda_di_iscrizione<\/a> (All. A-B-C) <\/em><\/span><\/p>\n<p><span style=\"color: #000080;\">\u00a0<\/span><\/p>\n<p><span style=\"color: #000080;\">\u00a0<\/span><\/p>\n<p><strong><span style=\"color: #ff0000;\">2.NEGOZIAZIONE ASSISTITA IN MATERIA DI FAMIGLIA (ART. 6, C. 3-TER, D.L. 132\/2014)<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000080;\">Si ricorda agli iscritti che gli <strong><span style=\"color: #333399;\">accordi di negoziazione assistita in materia di famiglia <\/span><\/strong>(art. 6 del DL 132\/2014, come modificato dal d.lgs. 149\/2022) <strong><span style=\"color: #333399;\">instaurati dal 1\u00b0 marzo 2023, devono essere trasmessi all\u2019indirizzo PEC dell\u2019Ordine<\/span><\/strong>, secondo quanto previsto al <strong><span style=\"color: #333399;\">comma 3ter <\/span><\/strong>del medesimo articolo: \u201c<em>L&#8217;accordo, munito di nullaosta o di autorizzazione, \u00e8 trasmesso senza indugio a mezzo posta elettronica certificata\u00a0 o\u00a0 con altro sistema elettronico di recapito certificato qualificato, a cura degli avvocati che lo hanno sottoscritto,\u00a0 al\u00a0 Consiglio\u00a0 dell&#8217;Ordine presso\u00a0 cui\u00a0 \u00e8\u00a0 iscritto\u00a0 uno\u00a0 degli\u00a0 avvocati,\u00a0 che\u00a0 ne\u00a0\u00a0 cura\u00a0\u00a0 la conservazione in apposito\u00a0 archivio.\u00a0 Il Consiglio dell&#8217;Ordine, se richiesto, rilascia copia autentica dell&#8217;accordo alle parti e ai difensori che lo hanno sottoscritto<\/em>. <em>La conservazione ed esibizione dell&#8217;accordo \u00e8 disciplinata dall&#8217;articolo 43 del decreto legislativo 7 marzo 2005, n. 82.<\/em>\u201d<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000080;\">Si segnala che:<\/span><\/p>\n<ul>\n<li style=\"text-align: justify;\"><span style=\"color: #000080;\">l\u2019accordo deve essere firmato digitalmente dall\u2019avvocato che effettua la trasmissione al COA;<\/span><\/li>\n<li style=\"text-align: justify;\"><span style=\"color: #000080;\">il nullaosta (o autorizzazione) pu\u00f2 essere contenuto nello stesso file dell\u2019accordo, o in file separato, purch\u00e9 firmato digitalmente dalla Procura;<\/span><\/li>\n<li style=\"text-align: justify;\"><span style=\"color: #000080;\"><strong><span style=\"color: #333399;\">la trasmissione degli accordi di negoziazione assistita prevista dall\u2019art. 11, co. 1<\/span><\/strong>, della citata normativa, integra un adempimento distinto e ulteriore finalizzato alla raccolta dei dati statistici e <strong><span style=\"color: #333399;\">dovr\u00e0 essere comunque effettuata tramite la piattaforma CNF dedicata<\/span><\/strong>, accessibile al link: https:\/\/www.consiglionazionaleforense.it\/web\/cnf\/gestionale-deposito-accordi<\/span><\/li>\n<\/ul>\n<p><span style=\"color: #000080;\">\u00a0<\/span><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; \u00a0 Lettera informativa n. 106\/23 del 24.07.2023 \u00a0 \u00a0\u00a0 1.TRIBUNALE PESCARA \u2013 ISCRIZIONE \u00a0ELENCO 179 TER Si trasmettono il verbale della riunione 18.07.2023 del Comitato costituito ai sensi dell\u2019art. 179 ter secondo comma ed il successivo provvedimento 19.07.23 del Presidente del Tribunale di Pescara con allegata modulistica, recanti disposizioni sulle modalit\u00e0 di presentazione delle [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[],"_links":{"self":[{"href":"https:\/\/www.ordineavvocatipescara.it\/index.php\/wp-json\/wp\/v2\/posts\/22901"}],"collection":[{"href":"https:\/\/www.ordineavvocatipescara.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ordineavvocatipescara.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ordineavvocatipescara.it\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ordineavvocatipescara.it\/index.php\/wp-json\/wp\/v2\/comments?post=22901"}],"version-history":[{"count":7,"href":"https:\/\/www.ordineavvocatipescara.it\/index.php\/wp-json\/wp\/v2\/posts\/22901\/revisions"}],"predecessor-version":[{"id":22911,"href":"https:\/\/www.ordineavvocatipescara.it\/index.php\/wp-json\/wp\/v2\/posts\/22901\/revisions\/22911"}],"wp:attachment":[{"href":"https:\/\/www.ordineavvocatipescara.it\/index.php\/wp-json\/wp\/v2\/media?parent=22901"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ordineavvocatipescara.it\/index.php\/wp-json\/wp\/v2\/categories?post=22901"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ordineavvocatipescara.it\/index.php\/wp-json\/wp\/v2\/tags?post=22901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}