{"id":23492,"date":"2023-12-04T17:07:55","date_gmt":"2023-12-04T16:07:55","guid":{"rendered":"https:\/\/www.ordineavvocatipescara.it\/?p=23492"},"modified":"2023-12-04T17:07:55","modified_gmt":"2023-12-04T16:07:55","slug":"informativa-150-23-ruoli-sorv-aq-ruoli-immobiliari-elenco-179ter-aggiornato-e-versamento-concessione-governativa-odm-tabelle-indennita-valori-minimi-aiga-pe-banco-alimentare-siaa-toghe-pe","status":"publish","type":"post","link":"https:\/\/www.ordineavvocatipescara.it\/index.php\/2023\/12\/04\/informativa-150-23-ruoli-sorv-aq-ruoli-immobiliari-elenco-179ter-aggiornato-e-versamento-concessione-governativa-odm-tabelle-indennita-valori-minimi-aiga-pe-banco-alimentare-siaa-toghe-pe\/","title":{"rendered":"Informativa 150\/23 (RUOLI SORV AQ &#8211; RUOLI IMMOBILIARI &#8211; ELENCO 179TER AGGIORNATO E VERSAMENTO CONCESSIONE GOVERNATIVA &#8211; ODM TABELLE INDENNITA&#8217; VALORI MINIMI &#8211; AIGA PE BANCO ALIMENTARE &#8211; SIAA TOGHE PER UDIENZE TAR)"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><strong><span style=\"color: #000080;\">Lettera informativa n. 150\/23 del 04.12.2023<\/span><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong><span style=\"color: #ff0000;\">1.TRIBUNALE SORVEGLIANZA L\u2019AQUILA \u2013 RUOLI 5 DICEMBRE 2023<\/span><\/strong><\/p>\n<p><span style=\"color: #000080;\">Si trasmette in allegato:<\/span><\/p>\n<ul>\n<li><span style=\"color: #000080;\">ruolo udienza 05.12.23 <a href=\"https:\/\/www.ordineavvocatipescara.it\/wp-content\/uploads\/2023\/12\/RUOLO-UDIENZA-DEL-05_12_2024_B.pdf\">clicca qui<\/a>\u2013 fasce orarie <a href=\"https:\/\/www.ordineavvocatipescara.it\/wp-content\/uploads\/2023\/12\/FASCE-ORARIE-UDIENZA-DEL-05.12.2023_B.pdf\">clicca qui<\/a><br \/>\n<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong><span style=\"color: #ff0000;\">\u00a02.TRIBUNALE PESCARA \u2013 RUOLI UDIENZE IMMOBILIARI \u00a05-7 DICEMBRE 2023<\/span><\/strong><\/p>\n<p><span style=\"color: #000080;\">Con riferimento all\u2019oggetto, si trasmettono i seguenti documenti:<\/span><\/p>\n<p><span style=\"color: #000080;\">\u2013 ruolo COLANTONIO (5.12 <a href=\"https:\/\/www.ordineavvocatipescara.it\/wp-content\/uploads\/2023\/12\/ruolo-udienza-dr.-colantonio-5-12.pdf\">clicca qui<\/a> &#8211; 7.12 <a href=\"https:\/\/www.ordineavvocatipescara.it\/wp-content\/uploads\/2023\/12\/ruolo-udienza-dr.-colantonio-7-12.pdf\">clicca qui<\/a>)<\/span><\/p>\n<p><span style=\"color: #000080;\">\u2013 ruolo MARGANELLA (5.12 <a href=\"https:\/\/www.ordineavvocatipescara.it\/wp-content\/uploads\/2023\/12\/ruolo-udienza-dr.-marganella-5-12.pdf\">clicca qui<\/a> &#8211; 7.12 <a href=\"https:\/\/www.ordineavvocatipescara.it\/wp-content\/uploads\/2023\/12\/udienza-dr.-marganella-7-12.pdf\">clicca qui<\/a>)<\/span><\/p>\n<p><span style=\"color: #000080;\">\u00a0<\/span><\/p>\n<p><strong><span style=\"color: #ff0000;\">\u00a03.TRIBUNALE PESCARA \u2013 ELENCO AGGIORNATO PROFESSIONISTI DELEGATI ART. 179 TER &#8211; CHIARIMENTI ISCRIZIONE<br \/>\n<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000080;\">Si trasmette in allegato, pervenuto dal Tribunale di Pescara, l\u2019Elenco aggiornato (<em>v. lett. info n. 144\/23 del 20.11.23<\/em>) dei Professionisti Delegati alle Operazioni di Vendita (All. A), approvato dal Comitato di cui all\u2019art. 179-ter disp. att. c.p.c. riunitosi in data 28 novembre 2023. <a href=\"https:\/\/www.ordineavvocatipescara.it\/wp-content\/uploads\/2023\/12\/Elenco_Professionisti_-_28.11.2023.pdf\">CLICCA QUI<\/a><br \/>\n<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000080;\">Si segnala agli iscritti che, nella medesima seduta, il Comitato ha disposto che \u201c<strong><span style=\"color: #333399;\"><em>i professionisti iscritti debbano versare la tassa di concessione governativa di \u20ac 168,00 sul c\/c n. 8003<\/em><\/span><\/strong><em> intestato ad Agenzia Entrate Centro operativo di Pescara, ai sensi del punto 8 art. 22 della tariffa annessa al DPR 641 del 1972, <span style=\"color: #333399;\">entro 15 gg.<\/span> dalla comunicazione dell\u2019iscrizione da parte dei rispettivi ordini professionali e <strong><span style=\"color: #333399;\">riscontrando l\u2019avvenuto pagamento a mezzo pec al seguente indirizzo: <a style=\"color: #333399;\" href=\"mailto:prot.tribunale.pescara@giustiziacert.it\">prot.tribunale.pescara@giustiziacert.it<\/a>.<\/span><\/strong><\/em>\u201d<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000080;\">Il Presidente del Tribunale, a seguito di richiesta di chiarimenti da parte del COA in merito a quanto deliberato dal Comitato nella riunione del 28.11.23 su modalit\u00e0 di pagamento e conseguenze nel caso di omesso versamento, con nota 04.12.2023 ha precisato che:<\/span><\/p>\n<ul>\n<li style=\"text-align: justify;\"><span style=\"color: #000080;\">la comunicazione da parte di ciascun ordine professionale dell\u2019avvenuta iscrizione nell\u2019Elenco risponde all\u2019esigenza di una definizione in tempi brevi delle procedure relative ed ha carattere <strong><span style=\"color: #333399;\"><em>informale<\/em><\/span><\/strong>;<\/span><\/li>\n<li style=\"text-align: justify;\"><span style=\"color: #000080;\">il termine di 15 gg. fissato per il pagamento della tassa di concessione governativa \u00e8 <strong><span style=\"color: #333399;\"><em>meramente ordinatorio<\/em><\/span><\/strong>;<\/span><\/li>\n<li style=\"text-align: justify;\"><span style=\"color: #000080;\">dal tenore dell\u2019art. 2 DPR 641\/72, risulta evidente che \u201c<em>s<strong><span style=\"color: #333399;\">enza il pagamento della tassa non vi pu\u00f2 e non vi potr\u00e0 essere formale iscrizione abilitante per l\u2019assunzione di incarichi<\/span><\/strong><\/em><em> nella qualit\u00e0 di iscritto nell\u2019apposito Elenco\u201d<\/em>;<\/span><\/li>\n<li style=\"text-align: justify;\"><span style=\"color: #000080;\">di conseguenza, \u201c<em>\u00e8 interesse di ciascun professionista istante ammesso, abbia o non abbia avuto notizia dell\u2019ammissione all\u2019iscrizione, attivarsi per conoscere l\u2019esito della domanda, versare la tassa governativa, <strong><span style=\"color: #333399;\">documentarla alla Segreteria della Presidenza<\/span><\/strong>, cos\u00ec ottenendo l\u2019iscrizione nell\u2019Elenco di cui all\u2019art. 179-ter disp. att. c.p.c.\u201d. <\/em><\/span><span style=\"color: #000080;\"><a href=\"https:\/\/www.ordineavvocatipescara.it\/wp-content\/uploads\/2023\/12\/Nota_chiarimenti_4.12.23.pdf\">CLICCA QUI<\/a><\/span><\/li>\n<\/ul>\n<p><strong><span style=\"color: #ff0000;\">\u00a0<\/span><\/strong><\/p>\n<p><strong><span style=\"color: #ff0000;\">4.CAMERA DI CONCILIAZIONE FORENSE \u2013TABELLA SPESE DI MEDIAZIONE DM 150\/23 \u2013 VALORI MINIMI<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000080;\">Si segnala agli iscritti che, con delibera 23.11.23, a modifica di quanto precedentemente stabilito, le tabelle dei compensi per le indennit\u00e0 di mediazione di cui all\u2019art. 31, comma 1, del DM Giustizia n. 150\/23, sono state <strong><span style=\"color: #333399;\">quantificate nei valori minimi<\/span><\/strong>, in quanto maggiormente favorevoli ed al fine di promuovere e diffondere la cultura della mediazione. <a href=\"https:\/\/www.ordineavvocatipescara.it\/wp-content\/uploads\/2023\/12\/Istruzioni-per-il-deposito-in-vigore-dal-15.11.2023-valori-minimi.pdf\">CLICCA QUI<\/a><br \/>\n<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000080;\"><em>La tabella \u00e8 disponibile anche sul sito istituzionale dell\u2019Ordine www.ordineavvocatipescara.it, alla pagina <\/em>Organismi COA<em>, sez.\u00a0<\/em>Organismo di Mediazione<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><strong><span style=\"color: #ff0000;\">5.AIGA PESCARA \u2013 BANCO ALIMENTARE 7-14-21 DICEMBRE 2023<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000080;\">Si segnala agli iscritti che la sezione AIGA di Pescara ha organizzato, con il Banco Alimentare dell\u2019Abruzzo, una raccolta di generi alimentari in favore dei pi\u00f9 bisognosi, nei giorni 7-14-21 dicembre 2023, presso la propria sede (di fronte l\u2019Aula 1 civile del Tribunale). <a href=\"https:\/\/www.ordineavvocatipescara.it\/wp-content\/uploads\/2023\/12\/locandina-banco-alimentare-3.pdf\">CLICCA QUI<\/a><br \/>\n<\/span><\/p>\n<p><span style=\"color: #000080;\">\u00a0<\/span><span style=\"color: #000080;\">\u00a0<\/span><\/p>\n<p><strong><span style=\"color: #ff0000;\">6.SIAA \u2013 DISPONIBILITA\u2019 TOGHE PER UDIENZE TAR<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000080;\">Si segnala agli iscritti l\u2019iniziativa della Societ\u00e0 Italiana degli Avvocati Amministrativisti per la messa a disposizione di toghe presso le sedi dei Tribunali Amministrativi Regionali, ai fini dell\u2019utilizzo in udienza da parte degli avvocati che ne facciano richiesta.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Lettera informativa n. 150\/23 del 04.12.2023 &nbsp; 1.TRIBUNALE SORVEGLIANZA L\u2019AQUILA \u2013 RUOLI 5 DICEMBRE 2023 Si trasmette in allegato: ruolo udienza 05.12.23 clicca qui\u2013 fasce orarie clicca qui &nbsp; \u00a02.TRIBUNALE PESCARA \u2013 RUOLI UDIENZE IMMOBILIARI \u00a05-7 DICEMBRE 2023 Con riferimento all\u2019oggetto, si trasmettono i seguenti documenti: \u2013 ruolo COLANTONIO (5.12 clicca qui &#8211; 7.12 [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[],"_links":{"self":[{"href":"https:\/\/www.ordineavvocatipescara.it\/index.php\/wp-json\/wp\/v2\/posts\/23492"}],"collection":[{"href":"https:\/\/www.ordineavvocatipescara.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ordineavvocatipescara.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ordineavvocatipescara.it\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ordineavvocatipescara.it\/index.php\/wp-json\/wp\/v2\/comments?post=23492"}],"version-history":[{"count":6,"href":"https:\/\/www.ordineavvocatipescara.it\/index.php\/wp-json\/wp\/v2\/posts\/23492\/revisions"}],"predecessor-version":[{"id":23508,"href":"https:\/\/www.ordineavvocatipescara.it\/index.php\/wp-json\/wp\/v2\/posts\/23492\/revisions\/23508"}],"wp:attachment":[{"href":"https:\/\/www.ordineavvocatipescara.it\/index.php\/wp-json\/wp\/v2\/media?parent=23492"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ordineavvocatipescara.it\/index.php\/wp-json\/wp\/v2\/categories?post=23492"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ordineavvocatipescara.it\/index.php\/wp-json\/wp\/v2\/tags?post=23492"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}