{"id":23515,"date":"2023-12-05T16:02:41","date_gmt":"2023-12-05T15:02:41","guid":{"rendered":"https:\/\/www.ordineavvocatipescara.it\/?p=23515"},"modified":"2023-12-05T16:02:41","modified_gmt":"2023-12-05T15:02:41","slug":"informativa-151-23-elenchi-pss-2024-elenco-nazionale-difensori-dufficio","status":"publish","type":"post","link":"https:\/\/www.ordineavvocatipescara.it\/index.php\/2023\/12\/05\/informativa-151-23-elenchi-pss-2024-elenco-nazionale-difensori-dufficio\/","title":{"rendered":"Informativa 151\/23 (ELENCHI PSS 2024 &#8211; ELENCO NAZIONALE DIFENSORI D&#8217;UFFICIO)"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><strong><span style=\"color: #000080;\">Lettera informativa n. 151\/23 del 05.12.2023<\/span><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong><span style=\"color: #ff0000;\">1.ELENCHI PATROCINIO A SPESE DELLO STATO 2024<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000080;\"><strong><span style=\"color: #333399;\">Ai fini dell\u2019aggiornamento per l\u2019anno 2024 degli Elenchi<\/span> <span style=\"color: #333399;\">dei difensori abilitati al patrocinio a spese dello Stato<\/span><\/strong>, si ricorda ai Colleghi che:<\/span><\/p>\n<ul style=\"text-align: justify;\">\n<li><span style=\"color: #000080;\">le <strong><span style=\"color: #0000ff;\">DOMANDE DI ISCRIZIONE <\/span><\/strong>potranno essere presentate a partire d<strong><span style=\"color: #333399;\">al 15 dicembre 2023 e sino al 15 gennaio 2024<\/span><\/strong>, utilizzando il modello allegato. <a href=\"https:\/\/www.ordineavvocatipescara.it\/wp-content\/uploads\/2023\/12\/DOMANDA-INSERIMENTO-ELENCHI-2024.docx\">CLICCA QUI<\/a><\/span><\/li>\n<li><span style=\"color: #000080;\"><strong><span style=\"color: #0000ff;\">NON OCCORRE ISTANZA DI PERMANENZA PER GLI ELENCHI PSS<\/span><span style=\"color: #0000ff;\">: chi \u00e8 gi\u00e0 inserito negli elenchi NON dovr\u00e0 presentare alcuna istanza<\/span><\/strong>, <strong><span style=\"color: #333399;\">salvo che per chiedere l\u2019iscrizione in ulteriori materie.<\/span><\/strong><\/span><\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><span style=\"color: #000080;\">L\u2019Elenco sar\u00e0 rinnovato con decorrenza 31 gennaio 2024, secondo quanto previsto dall\u2019art. 81 co. 4 del DPR 115\/2002.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000080;\">\u00a0<\/span><span style=\"color: #000080;\">Si segnala che il COA, nella seduta del 30.11.2023, ha deliberato di confermare anche per quest\u2019anno &#8211; in deroga ai parametri C.O.F.A. 23.11.18 &#8211; la riduzione dei requisiti per l\u2019iscrizione con riguardo al numero dei procedimenti per ciascuna materia nonch\u00e9 (quale requisito alternativo ai procedimenti) dei crediti formativi nella materia di riferimento.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000080;\">Resta fermo il <strong><span style=\"color: #333399;\">requisito della regolarit\u00e0 formativa<\/span><\/strong>, che, ai fini dell\u2019iscrizione negli elenchi 2024, si riterr\u00e0 soddisfatto mediante <u>a<strong><span style=\"color: #333399;\">utocertificazione<\/span><\/strong><\/u><strong><span style=\"color: #333399;\"><u> attestante l\u2019assolvimento dell\u2019obbligo formativo per l\u2019anno concluso 2022<\/u> (<em>15 CF di cui 3 in mat. obbligatoria<\/em>)<\/span><\/strong>, come da modello allegato all\u2019istanza (<em>v. sopra<\/em>).<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong><span style=\"color: #ff0000;\">2.ELENCO NAZIONALE DIFENSORI D\u2019UFFICIO \u2013 PERMANENZA 2024<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000080;\">Si ricorda ai <strong><span style=\"color: #333399;\">difensori d\u2019ufficio<\/span><\/strong> che <strong><span style=\"color: #333399;\">le istanze di permanenza nell\u2019Elenco Unico Nazionale per l\u2019anno 2024 <\/span><\/strong>dovranno essere inderogabilmente presentate <strong><span style=\"color: #0000ff;\"><u>sulla piattaforma CNF<\/u><u> entro il 31 dicembre 2023<\/u>.<\/span><\/strong> (<em>Non sono tenuti a tale adempimento i difensori iscritti nell\u2019Elenco nel corrente anno 2023, in quanto l\u2019obbligo decorre a partire dall\u2019anno successivo a quello dell\u2019iscrizione. Fanno <strong><span style=\"color: #333399;\">ECCEZIONE <\/span><\/strong>le sole iscrizioni, deliberate dal CNF nel 2023, ma su istanze presentate nel 2022, quindi soggette all\u2019obbligo di permanenza entro il 31.12.23.)<\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000080;\"><strong><span style=\"color: #333399;\">I REQUISITI PER LA PERMANENZA<\/span><\/strong>, di cui agli artt. 5 e 6 del <a href=\"https:\/\/www.ordineavvocatipescara.it\/wp-content\/uploads\/2023\/12\/ALLEGATO-1-Regolamento-per-la-tenuta-e-laggiornamento-dellelenco-unico-nazionale.pdf\">Regolamento CNF<\/a>, sono i seguenti:<\/span><\/p>\n<ul style=\"text-align: justify;\">\n<li><span style=\"color: #000080;\"><em>non avere riportato sanzioni disciplinari definitive superiori all&#8217;avvertimento irrogate nei cinque anni precedenti la domanda con provvedimento definitivo;<\/em><\/span><\/li>\n<li><span style=\"color: #000080;\"><strong><span style=\"color: #333399;\"><em>(esercizio continuativo di attivit\u00e0 nel settore penale): <\/em><\/span><span style=\"color: #333399;\"><u>10 udienze penali nell\u2019anno <\/u><span style=\"color: #ff0000;\"><u>2023<\/u><\/span><u>,<\/u> cio\u00e8 nel medesimo anno<\/span><\/strong> di presentazione della dichiarazione di permanenza;<\/span><\/li>\n<li><span style=\"color: #000080;\"><strong><span style=\"color: #333399;\"><em>(adempimento dell\u2019obbligo formativo di cui all\u2019art. 11 L. 247\/12): <\/em><\/span><span style=\"color: #333399;\"><u> 15 crediti, 3 dei quali in mat. obbligatoria, nell\u2019anno <\/u><span style=\"color: #ff0000;\"><u>2022<\/u><\/span>, cio\u00e8 nell\u2019anno precedente<\/span><\/strong> la dichiarazione di permanenza. <\/span><span style=\"color: #000080;\"><strong><span style=\"color: #333399;\">A tal fine, occorre depositare presso la Segreteria dell\u2019Ordine<\/span><\/strong>, in forma cartacea o a mezzo PEC, <u>l\u2019<strong><span style=\"color: #0000ff;\">autocertificazione attestante l\u2019assolvimento dell\u2019obbligo formativo per l\u2019anno 2022<\/span><\/strong><\/u>, utilizzando il modello allegato. <a href=\"https:\/\/www.ordineavvocatipescara.it\/wp-content\/uploads\/2023\/12\/DICHIARAZIONE-ASSOLVIMENTO-OBBLIGO-FORMATIVO-2022.docx\">CLICCA QUI<\/a><br \/>\n<\/span><\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><span style=\"color: #000080;\">Si ricorda, infine, che <strong><span style=\"color: #333399;\">la mancata presentazione dell\u2019istanza di permanenza entro il termine previsto comporta, da parte del CNF, la cancellazione d\u2019ufficio dall\u2019Elenco<\/span><\/strong> (<em>art. 10 Reg. CNF; art. 29 co. 1-quinquies disp. att. cpp<\/em>).<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Lettera informativa n. 151\/23 del 05.12.2023 &nbsp; 1.ELENCHI PATROCINIO A SPESE DELLO STATO 2024 Ai fini dell\u2019aggiornamento per l\u2019anno 2024 degli Elenchi dei difensori abilitati al patrocinio a spese dello Stato, si ricorda ai Colleghi che: le DOMANDE DI ISCRIZIONE potranno essere presentate a partire dal 15 dicembre 2023 e sino al 15 gennaio [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[],"_links":{"self":[{"href":"https:\/\/www.ordineavvocatipescara.it\/index.php\/wp-json\/wp\/v2\/posts\/23515"}],"collection":[{"href":"https:\/\/www.ordineavvocatipescara.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ordineavvocatipescara.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ordineavvocatipescara.it\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ordineavvocatipescara.it\/index.php\/wp-json\/wp\/v2\/comments?post=23515"}],"version-history":[{"count":5,"href":"https:\/\/www.ordineavvocatipescara.it\/index.php\/wp-json\/wp\/v2\/posts\/23515\/revisions"}],"predecessor-version":[{"id":23521,"href":"https:\/\/www.ordineavvocatipescara.it\/index.php\/wp-json\/wp\/v2\/posts\/23515\/revisions\/23521"}],"wp:attachment":[{"href":"https:\/\/www.ordineavvocatipescara.it\/index.php\/wp-json\/wp\/v2\/media?parent=23515"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ordineavvocatipescara.it\/index.php\/wp-json\/wp\/v2\/categories?post=23515"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ordineavvocatipescara.it\/index.php\/wp-json\/wp\/v2\/tags?post=23515"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}