{"id":30262,"date":"2026-03-25T16:29:59","date_gmt":"2026-03-25T15:29:59","guid":{"rendered":"https:\/\/www.ordineavvocatipescara.it\/?p=30262"},"modified":"2026-03-25T16:29:59","modified_gmt":"2026-03-25T15:29:59","slug":"informativa-44-26-trib-pe-rettifica-comunicazione-interruzione-energia-elettrica-28-29-3-ruoli-tar-pe-ruoli-gip-convenzioni-lpu-cc-pescara-avvio-protocollo-prodigius","status":"publish","type":"post","link":"https:\/\/www.ordineavvocatipescara.it\/index.php\/2026\/03\/25\/informativa-44-26-trib-pe-rettifica-comunicazione-interruzione-energia-elettrica-28-29-3-ruoli-tar-pe-ruoli-gip-convenzioni-lpu-cc-pescara-avvio-protocollo-prodigius\/","title":{"rendered":"Informativa 44\/26 (TRIB PE RETTIFICA COMUNICAZIONE INTERRUZIONE ENERGIA ELETTRICA 28\/29.3 &#8211; RUOLI TAR PE &#8211; RUOLI GIP &#8211; CONVENZIONI LPU &#8211; CC PESCARA AVVIO PROTOCOLLO &#8220;PRODIGIUS&#8221;)"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><strong><span style=\"color: #000080;\">Lettera informativa n. 44\/26 del 25.03.2026 <\/span><\/strong><\/p>\n<p><span style=\"color: #000080;\">\u00a0<\/span><\/p>\n<p><strong><span style=\"color: #000080;\"><span style=\"color: #ff0000;\">1.TRIBUNALE PESCARA \u2013 RETTIFICA COMUNICAZIONE INTERRUZIONE ENERGIA ELETTRICA 28-29 MARZO 2026<\/span> <\/span><\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000080;\">Si segnala agli iscritti quanto comunicato dal Tribunale di Pescara in data odierna con la nota a mezzo email sotto riportata (<em>v. info n. 40\/26 del 18.03.2026<\/em>):<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #333399;\">\u201c<strong><span style=\"color: #000080;\"><em>A rettifica di quanto comunicato con la mail in calce riportata, si comunica che non si dar\u00e0 luogo a nessuna interruzione elettrica nelle giornate di sabato 28 marzo e domenica 29 marzo p.v. in quanto i lavori sono stati ultimati.<\/em><\/span><\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #333399;\"><span style=\"color: #666699;\"><em>Si comunica che come da richiesta del provveditorato alle opere pubbliche, al fine del collegamento dell\u2019impianto fotovoltaico, \u00e8 necessario assicurare la interruzione dell\u2019energia elettrica da venerd\u00ec 20 marzo ore 14 a sabato 21 marzo ore 20 nonch\u00e9 da sabato 28 marzo ore 12 a domenica 29 marzo ore 24. Si raccomanda di non sostare nel Palazzo durante la sospensione dell\u2019erogazione dell\u2019energia elettrica, essendo inattivi tutti i sistemi di allarme e di emergenza ivi inclusi gli ascensori e i telefoni. Seguir\u00e0 provvedimento relativo alle misure organizzative da adottare per i settori Gip Gup e Dibattimento al fine di assicurare le attivit\u00e0 indifferibili e urgenti<\/em>.<\/span>\u201d<\/span><\/p>\n<p><span style=\"color: #000080;\">\u00a0<\/span><span style=\"color: #000080;\">\u00a0<\/span><\/p>\n<p><strong><span style=\"color: #ff0000;\">2.TAR PESCARA \u2013 RUOLI 27 MARZO 2026<\/span><\/strong><\/p>\n<p><span style=\"color: #000080;\">Con riferimento all\u2019oggetto, si trasmettono i seguenti documenti:<\/span><\/p>\n<ul>\n<li><span style=\"color: #000080;\">ruolo Camera di Consiglio 27.03.26 <a href=\"https:\/\/www.ordineavvocatipescara.it\/wp-content\/uploads\/2026\/03\/ruolo-camera-di-consiglio-27.3.pdf\">clicca qui<\/a><\/span><\/li>\n<li><span style=\"color: #000080;\">ruolo Udienza Pubblica 27.03.26 <a href=\"https:\/\/www.ordineavvocatipescara.it\/wp-content\/uploads\/2026\/03\/ruolo-udienza-pubblica-27.3.pdf\">clicca qui<\/a><\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong><span style=\"color: #ff0000;\">3.<\/span><\/strong><strong><span style=\"color: #000080;\"><span style=\"color: #ff0000;\">RUOLI UDIENZE UFFICIO GIP\/GUP PESCARA<\/span> <\/span><\/strong><\/p>\n<p><span style=\"color: #000080;\">Con riferimento all\u2019oggetto, si trasmettono i seguenti documenti:<\/span><\/p>\n<ul>\n<li><span style=\"color: #000080;\">ruolo SACCO (26.03.26 <a href=\"https:\/\/www.ordineavvocatipescara.it\/wp-content\/uploads\/2026\/03\/STATINO-ORDINE-26.3-gip-sacco.pdf\">clicca qui<\/a>)<\/span><\/li>\n<\/ul>\n<p><span style=\"color: #000080;\">\u00a0<\/span><\/p>\n<p><strong><span style=\"color: #ff0000;\">4.TRIBUNALE PESCARA \u2013 CONVENZIONI LAVORI PUBBLICA UTILITA\u2019<\/span><\/strong><\/p>\n<p><span style=\"color: #000080;\">Convenzioni LPU \u2013MAP:<\/span><\/p>\n<ul>\n<li><span style=\"color: #000080;\">Convenzione TRIBUNALE DI PESCARA\/Comune di CITTA\u2019 SANT\u2019ANGELO <a href=\"https:\/\/www.ordineavvocatipescara.it\/wp-content\/uploads\/2026\/03\/Convenzione_17650292_signed.pdf\">clicca qui<\/a><\/span><\/li>\n<\/ul>\n<p><span style=\"color: #000080;\">\u00a0<\/span><\/p>\n<p><strong><span style=\"color: #ff0000;\">5.<\/span><\/strong><strong><span style=\"color: #000080;\"><span style=\"color: #ff0000;\">CASA CIRCONDARIALE PESCARA \u2013 AVVIO PROTOCOLLO \u201cPRODIGIUS\u201d DAL 26.3.2026 \u2013 INDIRIZZI PEC<\/span> <\/span><\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000080;\">Si trasmette in allegato la nota della Direzione della Casa Circondariale di Pescara ad oggetto \u201c<em>Avvio protocollo \u201cProDiGius\u201d presso il Provveditorato Regionale dell\u2019Amministrazione penitenziaria per la Casa Circondariale di Pescara<\/em>\u201d, recante gli indirizzi PEC da utilizzare per l\u2019invio di atti e documenti a partire <strong><span style=\"color: #333399;\">dal 26.03.2026<\/span><\/strong>. <a href=\"https:\/\/www.ordineavvocatipescara.it\/wp-content\/uploads\/2026\/03\/img20260320_08265531.pdf\">CLICCA QUI<\/a><\/span><\/p>\n<p><span style=\"color: #000080;\">\u00a0<\/span><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Lettera informativa n. 44\/26 del 25.03.2026 \u00a0 1.TRIBUNALE PESCARA \u2013 RETTIFICA COMUNICAZIONE INTERRUZIONE ENERGIA ELETTRICA 28-29 MARZO 2026 Si segnala agli iscritti quanto comunicato dal Tribunale di Pescara in data odierna con la nota a mezzo email sotto riportata (v. info n. 40\/26 del 18.03.2026): \u201cA rettifica di quanto comunicato con la mail in [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[],"_links":{"self":[{"href":"https:\/\/www.ordineavvocatipescara.it\/index.php\/wp-json\/wp\/v2\/posts\/30262"}],"collection":[{"href":"https:\/\/www.ordineavvocatipescara.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ordineavvocatipescara.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ordineavvocatipescara.it\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ordineavvocatipescara.it\/index.php\/wp-json\/wp\/v2\/comments?post=30262"}],"version-history":[{"count":3,"href":"https:\/\/www.ordineavvocatipescara.it\/index.php\/wp-json\/wp\/v2\/posts\/30262\/revisions"}],"predecessor-version":[{"id":30270,"href":"https:\/\/www.ordineavvocatipescara.it\/index.php\/wp-json\/wp\/v2\/posts\/30262\/revisions\/30270"}],"wp:attachment":[{"href":"https:\/\/www.ordineavvocatipescara.it\/index.php\/wp-json\/wp\/v2\/media?parent=30262"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ordineavvocatipescara.it\/index.php\/wp-json\/wp\/v2\/categories?post=30262"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ordineavvocatipescara.it\/index.php\/wp-json\/wp\/v2\/tags?post=30262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}